{"id":45,"name":"Jose Antonio Font","url":"http:\/\/www.uv.es\/jofontro\/","description":"Jose Antonio Font es Profesor Titular del Departamento de Astronom\u00eda y Astrof\u00edsica de la Universitat de Val\u00e8ncia, del cual es actualmente su Director. Su \u00e1rea de investigaci\u00f3n es la Astrof\u00edsica Relativista, concretamente el estudio de objetos compactos (estrellas de neutrones\r\ny agujeros negros) y radiaci\u00f3n gravitatoria. En el periodo 2009-2013 Font fue Presidente de la Sociedad Espa\u00f1ola de Gravitaci\u00f3n\r\ny Relatividad. Es miembro de la Virgo Collaboration y coordina las actividades del Valencia Virgo Group en dicha colaboraci\u00f3n.","link":"https:\/\/bloggy.ific.uv.es\/bloggy\/index.php\/author\/tonifont\/","slug":"tonifont","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/26f3d4d4c71a8f54c987ecf3d2905455?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/26f3d4d4c71a8f54c987ecf3d2905455?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/26f3d4d4c71a8f54c987ecf3d2905455?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/bloggy.ific.uv.es\/bloggy\/index.php\/wp-json\/wp\/v2\/users\/45"}],"collection":[{"href":"https:\/\/bloggy.ific.uv.es\/bloggy\/index.php\/wp-json\/wp\/v2\/users"}]}}